{"id":7972,"date":"2015-10-05T11:00:43","date_gmt":"2015-10-05T14:00:43","guid":{"rendered":"http:\/\/www.campal.com.br\/site\/app\/webroot\/blog\/?p=2761"},"modified":"2015-10-05T11:00:43","modified_gmt":"2015-10-05T14:00:43","slug":"governo-altera-ir-sobre-ganho-de-capital-e-prorroga-o-prorelit","status":"publish","type":"post","link":"https:\/\/www.campal.com.br\/site\/governo-altera-ir-sobre-ganho-de-capital-e-prorroga-o-prorelit\/","title":{"rendered":"Aumento do IR sobre ganho de capital e prorroga\u00e7\u00e3o do Prorelit"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignright\" alt=\"\" src=\"http:\/\/www.contabeis.com.br\/Arquivar\/_resources\/newsimages\/804a32143d8743799d70d0082001971d.jpg\" width=\"300\" height=\"192\" \/>A Medida Provis\u00f3ria\u00a0692\/2015, publicada em edi\u00e7\u00e3o extra do Di\u00e1rio Oficial da Uni\u00e3o de 22-9, altera, a partir de 2016, a tributa\u00e7\u00e3o do\u00a0<a href=\"http:\/\/www.contabeis.com.br\/termos-contabeis\/imposto_de_renda\">Imposto de Renda<\/a>\u00a0sobre o\u00a0<a href=\"http:\/\/www.contabeis.com.br\/termos-contabeis\/ganho_de_capital\">ganho de capital<\/a>\u00a0percebido por pessoa f\u00edsica em decorr\u00eancia da aliena\u00e7\u00e3o de bens e direitos de qualquer natureza, conforme as seguintes al\u00edquotas:<br \/>\n&#8211; 15% sobre a parcela dos ganhos que n\u00e3o ultrapassar R$ 1.000.000,00;<br \/>\n&#8211; 20% sobre a parcela dos ganhos que exceder R$ 1.000.000,00 e n\u00e3o ultrapassar R$ 5.000.000,00;<br \/>\n&#8211; 25% sobre a parcela dos ganhos que exceder R$ 5.000.000,00 e n\u00e3o ultrapassar R$ 20.000.000,00 ; e<br \/>\n&#8211; 30% sobre a parcela dos ganhos que ultrapassar R$ 20.000.000,00.<br \/>\nAs novas al\u00edquotas ser\u00e3o aplicadas tamb\u00e9m, a partir de 2016, ao\u00a0<a href=\"http:\/\/www.contabeis.com.br\/termos-contabeis\/ganho_de_capital\">ganho de capital<\/a>\u00a0percebido por pessoa jur\u00eddica em decorr\u00eancia da aliena\u00e7\u00e3o de bens e direitos do Ativo N\u00e3o Circulante, exceto as tributadas pelo\u00a0<a href=\"http:\/\/www.contabeis.com.br\/termos-contabeis\/lucro_real\">lucro real,<\/a>\u00a0presumido ou arbitrado.<br \/>\nA MP 692 tamb\u00e9m alterou o prazo de ades\u00e3o ao Programa de Redu\u00e7\u00e3o de Lit\u00edgios Tribut\u00e1rios (Prorelit), institu\u00eddo pela Medida Provis\u00f3ria 685\/2015, para at\u00e9 30 de outubro de 2015 e o pagamento m\u00ednimo em esp\u00e9cie para:<br \/>\n&#8211; 30% do valor consolidado dos d\u00e9bitos indicados para a quita\u00e7\u00e3o, a ser efetuado at\u00e9 30 de outubro de 2015;<br \/>\n&#8211; 33% do valor consolidado dos d\u00e9bitos indicados para a quita\u00e7\u00e3o, a ser efetuado em duas parcelas venc\u00edveis at\u00e9 o \u00faltimo dia \u00fatil dos meses de outubro e novembro de 2015; ou<br \/>\n&#8211; 36% do valor consolidado dos d\u00e9bitos indicados para a quita\u00e7\u00e3o, a ser efetuado em tr\u00eas parcelas venc\u00edveis at\u00e9 o \u00faltimo dia \u00fatil dos meses de outubro, novembro e dezembro de 2015.<br \/>\nO valor de cada parcela mensal, por ocasi\u00e3o do pagamento de que tratam os percentuais de 33% e 36%, ser\u00e1 acrescido de\u00a0<a href=\"http:\/\/www.contabeis.com.br\/termos-contabeis\/juros\">juros<\/a>equivalentes \u00e0 taxa referencial do\u00a0<a href=\"http:\/\/www.contabeis.com.br\/termos-contabeis\/selic\">Selic<\/a>\u00a0para t\u00edtulos federais, acumulada mensalmente, calculados a partir do m\u00eas subsequente ao da consolida\u00e7\u00e3o at\u00e9 o m\u00eas anterior ao do pagamento, e de 1% relativamente ao m\u00eas em que o pagamento estiver sendo efetuado.<br \/>\nFonte: Coad<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Medida Provis\u00f3ria\u00a0692\/2015, publicada em edi\u00e7\u00e3o extra do Di\u00e1rio Oficial da Uni\u00e3o de 22-9, altera, a partir de 2016, a tributa\u00e7\u00e3o do\u00a0Imposto [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2773,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"iawp_total_views":0,"footnotes":""},"categories":[25],"tags":[],"class_list":["post-7972","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-campal"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.campal.com.br\/site\/wp-json\/wp\/v2\/posts\/7972","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.campal.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.campal.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.campal.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.campal.com.br\/site\/wp-json\/wp\/v2\/comments?post=7972"}],"version-history":[{"count":0,"href":"https:\/\/www.campal.com.br\/site\/wp-json\/wp\/v2\/posts\/7972\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.campal.com.br\/site\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/www.campal.com.br\/site\/wp-json\/wp\/v2\/media?parent=7972"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.campal.com.br\/site\/wp-json\/wp\/v2\/categories?post=7972"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.campal.com.br\/site\/wp-json\/wp\/v2\/tags?post=7972"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}