{"id":8024,"date":"2016-06-29T09:20:21","date_gmt":"2016-06-29T12:20:21","guid":{"rendered":"http:\/\/www.campal.com.br\/site\/app\/webroot\/blog\/?p=3445"},"modified":"2016-06-29T09:20:21","modified_gmt":"2016-06-29T12:20:21","slug":"lar-sao-vicente-sob-nova-direcao-pamela-campos-e-nova-presidente","status":"publish","type":"post","link":"https:\/\/www.campal.com.br\/site\/lar-sao-vicente-sob-nova-direcao-pamela-campos-e-nova-presidente\/","title":{"rendered":"Lar S\u00e3o Vicente sob nova Dire\u00e7\u00e3o, P\u00e2mela Campos \u00e9 nova presidente"},"content":{"rendered":"<p><div id=\"attachment_3454\" style=\"width: 635px\" class=\"wp-caption aligncenter\"><img fetchpriority=\"high\" decoding=\"async\" aria-describedby=\"caption-attachment-3454\" class=\"size-large wp-image-3454\" alt=\"13522814_886555251449955_6256854859244777305_o\" src=\"http:\/\/www.campal.com.br\/site\/app\/webroot\/blog\/wp-content\/uploads\/2016\/06\/13522814_886555251449955_6256854859244777305_o-1024x692.jpg\" width=\"625\" height=\"422\" \/><p id=\"caption-attachment-3454\" class=\"wp-caption-text\">Vice-Presidente I Carolina de F\u00e1tima Leie<br \/>Vice-Presidente II Catia Andrea Muller<br \/>Secret\u00e1rio I Dion\u00e9a Clarissa de Souza<br \/>Secret\u00e1rio II \u00c2ngela Nath\u00e1lia K\u00fcchle<br \/>Tesoureiro I Carla In\u00eas Brock<br \/>Tesoureiro II Jos\u00e9 Ernane Moraes Filho<\/p><\/div><br \/>\nH\u00e1 quase 30 anos, a comunidade hamburguense percebeu a necessidade de se preencher uma lacuna na assist\u00eancia aos idosos carentes de Novo Hamburgo.<br \/>\nA partir da\u00ed, um grupo de volunt\u00e1rios come\u00e7ou a mexer os pauzinhos&#8230; a Prefeitura de Novo Hamburgo cedeu, em regime de comodato, o terreno, e a comunidade doou materiais e m\u00e3o de obra para a constru\u00e7\u00e3o do Lar.<br \/>\nEm 16 de outubro de 1989 o Lar foi fundado, como uma Associa\u00e7\u00e3o de direito privado, sem fins lucrativos, criada pela comunidade hamburguense, para os idosos hamburguenses, e mantida por essa mesma comunidade, que compreende o papel essencial do Lar na vida de dezenas de idosos da nossa cidade.<br \/>\nTodos os vov\u00f4s que moram no Lar S\u00e3o Vicente s\u00e3o convidados a doar sua aposentadoria em prol das despesas do estabelecimento. Contudo, muitos recebem apenas 1 sal\u00e1rio m\u00ednimo mensal, outros tem esse sal\u00e1rio comprometido com financiamentos, e outros, ainda, sequer recebem qualquer benef\u00edcio do INSS para colaborar. Por esse motivo, as doa\u00e7\u00f5es da comunidade se tornam essenciais para a manuten\u00e7\u00e3o do Lar, que conta com uma despesa m\u00e9dia, por vov\u00f4, de aproximadamente R$3.500,00 mensais, incluindo alimenta\u00e7\u00e3o, servi\u00e7o m\u00e9dico, rem\u00e9dios, fraldas, contrata\u00e7\u00e3o de funcion\u00e1rios habilitados (enfermeiros, t\u00e9cnicos, cozinheiras, etc.), cal\u00e7ados, lazer, manuten\u00e7\u00e3o do pr\u00e9dio, dentre tantas outras despesas.<br \/>\nPor esse motivo, as a\u00e7\u00f5es desenvolvidas pelo Lar, com o apoio da comunidade, s\u00e3o t\u00e3o importantes. Festas e jantares beneficentes, meio frango, brech\u00f3s, etc. Todos eles com o intuito de ajudar na arrecada\u00e7\u00e3o financeira e no pagamento das contas da Institui\u00e7\u00e3o, que, apesar de carente, preza e se orgulha do excelente trabalho desenvolvido junto aos vov\u00f4s.<br \/>\nA Campal, como apoiadora do Lar S\u00e3o Vicente, convida seus clientes \u00e0 se engajar nessa nobre causa, que conta, desde o dia 26\/06\/2016, com uma representante da Campal em sua Diretoria Executiva, cujo servi\u00e7o \u00e9 volunt\u00e1rio. P\u00e2mela de Campos \u00e9 a nova Presidente do Lar S\u00e3o Vicente de Paula, na Gest\u00e3o 2016\/2018, cuja Diretoria conta, ainda, com os seguintes membros:<br \/>\n&nbsp;<\/p>\n<table width=\"425\" border=\"0\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr>\n<td valign=\"bottom\" nowrap=\"nowrap\" width=\"177\">Vice-Presidente I<\/td>\n<td valign=\"bottom\" nowrap=\"nowrap\" width=\"248\">Carolina de F\u00e1tima Leie<\/td>\n<\/tr>\n<tr>\n<td valign=\"bottom\" nowrap=\"nowrap\" width=\"177\">Vice-Presidente II<\/td>\n<td valign=\"bottom\" nowrap=\"nowrap\" width=\"248\">Catia Andrea Muller<\/td>\n<\/tr>\n<tr>\n<td valign=\"bottom\" nowrap=\"nowrap\" width=\"177\">Secret\u00e1rio I<\/td>\n<td valign=\"bottom\" nowrap=\"nowrap\" width=\"248\">Dion\u00e9a Clarissa de Souza<\/td>\n<\/tr>\n<tr>\n<td valign=\"bottom\" nowrap=\"nowrap\" width=\"177\">Secret\u00e1rio II<\/td>\n<td valign=\"bottom\" nowrap=\"nowrap\" width=\"248\">\u00c2ngela Nath\u00e1lia K\u00fcchle<\/td>\n<\/tr>\n<tr>\n<td valign=\"bottom\" nowrap=\"nowrap\" width=\"177\">Tesoureiro I<\/td>\n<td valign=\"bottom\" nowrap=\"nowrap\" width=\"248\">Carla In\u00eas Brock<\/td>\n<\/tr>\n<tr>\n<td valign=\"bottom\" nowrap=\"nowrap\" width=\"177\">Tesoureiro II<\/td>\n<td valign=\"bottom\" nowrap=\"nowrap\" width=\"248\">Jos\u00e9 Ernane Moraes Filho<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>Porque fazer o bem \u00e9 tudo de bom.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>H\u00e1 quase 30 anos, a comunidade hamburguense percebeu a necessidade de se preencher uma lacuna na assist\u00eancia aos idosos carentes de Novo [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3454,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"iawp_total_views":8,"footnotes":""},"categories":[25],"tags":[],"class_list":["post-8024","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-campal"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.campal.com.br\/site\/wp-json\/wp\/v2\/posts\/8024","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.campal.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.campal.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.campal.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.campal.com.br\/site\/wp-json\/wp\/v2\/comments?post=8024"}],"version-history":[{"count":0,"href":"https:\/\/www.campal.com.br\/site\/wp-json\/wp\/v2\/posts\/8024\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.campal.com.br\/site\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/www.campal.com.br\/site\/wp-json\/wp\/v2\/media?parent=8024"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.campal.com.br\/site\/wp-json\/wp\/v2\/categories?post=8024"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.campal.com.br\/site\/wp-json\/wp\/v2\/tags?post=8024"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}